{"id":1533,"date":"2022-10-18T16:16:58","date_gmt":"2022-10-18T15:16:58","guid":{"rendered":"https:\/\/www.lbi.fr\/?page_id=1533"},"modified":"2022-10-21T10:15:33","modified_gmt":"2022-10-21T09:15:33","slug":"elektrische-komponenten","status":"publish","type":"page","link":"https:\/\/www.lbi.fr\/de\/anwendungsbereiche\/elektrische-komponenten\/","title":{"rendered":"Elektrische Komponenten"},"content":{"rendered":"<h1><span class=\"uk-text-primary\">Elektrische<\/span> Bauteile<\/h1>\n<div>\n<p>Au\u00dfendurchmesser bis zu 6.000 mm &#8211; L\u00e4nge von 4 mm bis 4.500 mm<\/p>\n<\/div>\n<h2>Hohe Ma\u00dfhaltigkeit<\/h2>\n<h2>Gro\u00dfe Bandbreite an Abmessungen<\/h2>\n<h2>Anpassungsf\u00e4higkeit des Prozesses an spezielle Produkte<\/h2>\n<h2>Langj\u00e4hrige Erfahrung und anerkanntes Know-how<\/h2>\n<h2>Kosteng\u00fcnstige L\u00f6sung in Bezug auf Material und Bearbeitung<\/h2>\n<h2>Beispiele f\u00fcr die Anwendung<\/h2>\n<hr>\n<ul>\n<li>\n<p>        <img decoding=\"async\" src=\"\/wp-content\/uploads\/LBI-Domaines-dapplication-Composants-e%CC%81lectriques-bagues-collectrices.jpg\" alt=\"Les Bronzes d'Industrie - Anwendungsbereiche - Elektrische Komponenten - Schleifringe\"><\/p>\n<\/li>\n<li>\n<p>        <img decoding=\"async\" src=\"\/wp-content\/uploads\/LBI-Domaines-dapplication-Composants-e%CC%81lectriques-bagues-collectrices-03.jpg\" alt=\"Les Bronzes d'Industrie - Anwendungsbereiche - Elektrische Komponenten - Schleifringe\"><\/p>\n<\/li>\n<li>\n<p>        <img decoding=\"async\" src=\"\/wp-content\/uploads\/LBI-Domaines-dapplication-Composants-e%CC%81lectriques-bagues-collectrices-02.jpg\" alt=\"Les Bronzes d'Industrie - Anwendungsbereiche - Elektrische Komponenten - Schleifringe\"><\/p>\n<\/li>\n<\/ul>\n<h3>Schleifringe &#8211; Radial und axial<\/h3>\n<div>\n<div>\n<p>Bearbeitete Ringe mit Endbearbeitung oder roh bearbeitete Ringe<br \/>Materialien: Bronze, Messing, Kupferlegierungen, Sonderlegierungen<\/p>\n<\/div>\n<\/div>\n<ul>\n<li>\n<p>        <img decoding=\"async\" src=\"\/wp-content\/uploads\/LBI-Domaines-dapplication-Composants-e%CC%81lectriques-Tube-pour-ligne-de%CC%81lectrozingage.jpg\" alt=\"Les Bronzes d'Industrie - Anwendungsbereiche - Elektrische Komponenten - Rohr f\u00fcr Elektroverzinkungsanlagen\"><\/p>\n<\/li>\n<li>\n<p>        <img decoding=\"async\" src=\"\/wp-content\/uploads\/LBI-Domaines-dapplication-Composants-e%CC%81lectriques-Collecteur-lignes-de%CC%81lectrozingage.jpg\" alt=\"Les Bronzes d'Industrie - Anwendungsbereiche - Elektrische Komponenten - Kollektor f\u00fcr Elektroverzinkungsleitungen\"><\/p>\n<\/li>\n<\/ul>\n<h3>Kollektoren und Rohre f\u00fcr Elektroverzinkungsanlagen<\/h3>\n<div>\n<div>\n<p>Material: Reines Kupfer<\/p>\n<\/div>\n<\/div>\n<p><a href=\"\/wp-content\/uploads\/LBI-Domaines-dapplication-Composants-e%CC%81lectriques-Douilles-de-disjoncteur.jpg\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/LBI-Domaines-dapplication-Composants-e%CC%81lectriques-Douilles-de-disjoncteur.jpg\" alt=\"Les Bronzes d'Industrie - Anwendungsbereiche - Elektrische Komponenten - Unterbrecherbuchsen f\u00fcr Kraftwerke\"><\/a><\/p>\n<h3>Kurzschlussringe f\u00fcr Kraftwerke<\/h3>\n<div>\n<div>\n<p>Material: Kupferlegierungen oder reines Kupfer<\/p>\n<\/div>\n<\/div>\n<p><a href=\"\/wp-content\/uploads\/LBI-Domaines-dapplication-Composants-e%CC%81lectriques-Anneau-de-disjoncteur.jpg\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/LBI-Domaines-dapplication-Composants-e%CC%81lectriques-Anneau-de-disjoncteur.jpg\" alt=\"Les Bronzes d'Industrie - Anwendungsbereiche - Elektrische Komponenten - Leistungsschalter f\u00fcr Kraftwerke\"><\/a><\/p>\n<h3>Ringe f\u00fcr Leistungsschalter f\u00fcr Kraftwerke<\/h3>\n<div>\n<div>\n<p>Material: Kupferlegierungen oder reines Kupfer<\/p>\n<\/div>\n<\/div>\n<h2>Materialien und Ausf\u00fchrung<\/h2>\n<hr>\n<h3>Vorgeschlagene Legierungen<\/h3>\n<ul>\n<li>\n<div>\n<p>Messing<\/p>\n<\/div>\n<\/li>\n<li>\n<div>\n<p>Zinnbronze<\/p>\n<\/div>\n<\/li>\n<li>\n<div>\n<p>Reines Kupfer<\/p>\n<\/div>\n<\/li>\n<li>\n<div>\n<p>Kupferlegierungen<\/p>\n<\/div>\n<\/li>\n<li>\n<div>\n<p>Nach Ihren W\u00fcnschen<\/p>\n<\/div>\n<\/li>\n<\/ul>\n<h3>Fertigung<\/h3>\n<ul>\n<li>\n<div>\n<p>Vorbearbeiten<\/p>\n<\/div>\n<\/li>\n<li>\n<div>\n<p>Teilweise oder vollst\u00e4ndige Bearbeitung<\/p>\n<\/div>\n<\/li>\n<\/ul>\n<p><a href=\"\/wp-content\/uploads\/LBI-Produits-Alliages-cuivreux-Galeries-photos-04.jpg\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/LBI-Produits-Alliages-cuivreux-Galeries-photos-04.jpg\" alt=\"Les Bronzes d'Industrie - Anwendungsbereiche - Elektrische Komponenten\"><\/a><\/p>\n<h2>Andere Anwendungsbereiche<\/h2>\n<hr>\n<ul>\n<li>\n<p>        <img decoding=\"async\" src=\"\/wp-content\/uploads\/LBI-Domaines-dapplication-Construction-navale-Galeries-photos-01.jpg\" alt=\"Les Bronzes d'Industrie - Anwendungsbereiche - Schiffbau\"><\/p>\n<h3>Schiffbau<\/h3>\n<p><a href=\"\/de\/anwendungsbereiche\/schiffbau\/\"><\/a><\/p>\n<\/li>\n<li>\n<p>        <img decoding=\"async\" src=\"\/wp-content\/uploads\/LBI-Domaines-dapplication-Turbines-Galeries-photos-01.jpg\" alt=\"Les Bronzes d'Industrie - Anwendungsbereiche - Turbinen\"><\/p>\n<h3>Turbinen<\/h3>\n<p><a href=\"\/de\/anwendungsbereiche\/turbinen\/\"><\/a><\/p>\n<\/li>\n<li>\n<p>        <img decoding=\"async\" src=\"\/wp-content\/uploads\/LBI-Domaines-dapplication-Aeronautique-Galeries-photos-01.jpg\" alt=\"Les Bronzes d'Industrie - Anwendungsbereiche - Luft- und Raumfahrt\"><\/p>\n<h3>Luft- und Raumfahrt<\/h3>\n<p><a href=\"\/de\/anwendungsbereiche\/luft-und-raumfahrt\/\"><\/a><\/p>\n<\/li>\n<li>\n<p>        <img decoding=\"async\" src=\"\/wp-content\/uploads\/LBI-Domaines-dapplication-Chimie-Galeries-photos-01.jpg\" alt=\"Les Bronzes d'Industrie - Anwendungsbereiche - Chemie\"><\/p>\n<h3>Chemie<\/h3>\n<p><a href=\"\/de\/anwendungsbereiche\/chemie\/\"><\/a><\/p>\n<\/li>\n<li>\n<p>        <img decoding=\"async\" src=\"\/wp-content\/uploads\/LBI-Domaines-dapplication-Siderurgie-Galvanisation-Galeries-photos-01.jpg\" alt=\"Les Bronzes d'Industrie - Anwendungsbereiche - Eisen- und Stahlindustrie \/ Galvanisierung\"><\/p>\n<h3>Eisen- und Stahlindustrie \/ Galvanisierung<\/h3>\n<p><a href=\"\/de\/anwendungsbereiche\/eisen-und-stahlindustrie-galvanisierung\/\"><\/a><\/p>\n<\/li>\n<li>\n<p>        <img decoding=\"async\" src=\"\/wp-content\/uploads\/LBI-Domaines-dapplication-Siderurgie-Laminage-Galeries-photos-01-1.jpg\" alt=\"Les Bronzes d'Industrie - Anwendungsbereiche - Eisen- und Stahlindustrie \/ Walzen\"><\/p>\n<h3>Eisen- und Stahlindustrie \/ Walzen<\/h3>\n<p><a href=\"\/de\/anwendungsbereiche\/eisen-und-stahlindustrie-walzen\/\"><\/a><\/p>\n<\/li>\n<li>\n<p>        <img decoding=\"async\" src=\"\/wp-content\/uploads\/LBI-Domaines-dapplication-Broyage-Galeries-photos-01.jpg\" alt=\"Les Bronzes d'Industrie - Anwendungsbereiche - Zerkleinern \/ Bergbau\"><\/p>\n<h3>Zerkleinern \/ Bergbau<\/h3>\n<p><a href=\"\/de\/anwendungsbereiche\/zerkleinerung-bergbau\/\"><\/a><\/p>\n<\/li>\n<li>\n<p>        <img decoding=\"async\" src=\"\/wp-content\/uploads\/LBI-Domaines-dapplication-machine-outil-Galeries-photos-01.jpg\" alt=\"Les Bronzes d'Industrie - Anwendungsbereiche - Werkzeugmaschinen und Pressen Presses\"><\/p>\n<h3>Werkzeugmaschinen und Pressen<\/h3>\n<p><a href=\"\/de\/anwendungsbereiche\/werkzeugmaschinen-und-pressen\/\"><\/a><\/p>\n<\/li>\n<li>\n<p>        <img decoding=\"async\" src=\"\/wp-content\/uploads\/LBI-Domaine-dapplications-Pompes-Galeries-photos-01.jpg\" alt=\"Les Bronzes d'Industrie - Anwendungsbereiche - Pumpen\"><\/p>\n<h3>Pumpen<\/h3>\n<p><a href=\"\/de\/anwendungsbereiche\/pumpen\/\"><\/a><\/p>\n<\/li>\n<li>\n<p>        <img decoding=\"async\" src=\"\/wp-content\/uploads\/LBI-Domaines-dapplication-Vannes-Galeries-photos-01.jpg\" alt=\"Les Bronzes d'Industrie - Anwendungsbereiche - Armaturen &#038; Ventile\"><\/p>\n<h3>Armaturen &#038; Ventile<\/h3>\n<p><a href=\"\/de\/anwendungsbereiche\/armaturen-und-ventile\/\"><\/a><\/p>\n<\/li>\n<\/ul>\n<h2>Wichtigste Zulassungen<\/h2>\n<hr>\n<p>\n    <a href=\"\/de\/les-bronzes-dindustrie\/zertifizierungen-und-zulassungen\/\">Weitere Informationen<\/a>\n<\/p>\n<ul>\n<li>\n<p>        <img decoding=\"async\" src=\"\/wp-content\/uploads\/ISO-9001-Certification.png\" alt=\"Les Bronzes d'Industrie - Zertifizierung ISO 9001\"><\/p>\n<\/li>\n<li>\n<p>        <img decoding=\"async\" src=\"\/wp-content\/uploads\/ISO-14001-Certification.png\" alt=\"Les Bronzes d'Industrie - Zertifizierung ISO 14001\"><\/p>\n<\/li>\n<\/ul>\n<p><!--more--><br \/>\n<!-- {\"type\":\"layout\",\"children\":[{\"name\":\"Hero\",\"type\":\"section\",\"props\":{\"width\":\"default\",\"padding\":\"large\",\"style\":\"secondary\",\"media\":\"images\\\/casestudy-header.jpg\",\"image\":\"wp-content\\\/uploads\\\/LBI-Domaines-dapplication-Composants-e\\u0301lectriques-Bandeaux-01.jpg\",\"media_advanced\":true,\"image_size\":\"cover\",\"media_background\":\"#fff\",\"media_overlay\":\"rgba(0, 0, 0, 0.45)\",\"image_fixed\":true,\"image_position\":\"center-center\",\"vertical_align\":\"middle\",\"title_position\":\"top-left\",\"title_rotation\":\"left\",\"title_breakpoint\":\"xl\",\"media_blend_mode\":\"multiply\",\"header_transparent\":\"light\",\"header_transparent_noplaceholder\":false},\"children\":[{\"name\":\"\",\"type\":\"row\",\"children\":[{\"name\":\"\",\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"media_overlay_gradient\":\"\",\"width_medium\":\"1-1\",\"vertical_align\":\"middle\",\"position_sticky_breakpoint\":\"m\"},\"children\":[{\"name\":\"\",\"type\":\"headline\",\"props\":{\"title_element\":\"h1\",\"title_style\":\"heading-large\",\"text_align\":\"left\",\"content\":\"<span class=\\\"uk-text-primary\\\">Elektrische<\\\/span> Bauteile\",\"margin_remove_top\":true,\"css\":\".el-element .uk-text-primary {\\n    color: #FFB932 !important;\\n}\"}},{\"name\":\"\",\"type\":\"text\",\"props\":{\"column_breakpoint\":\"m\",\"text_align\":\"justify\",\"maxwidth\":\"xlarge\",\"margin\":\"\",\"content\":\"\n\n<p>Au\\u00dfendurchmesser bis zu 6.000 mm - L\\u00e4nge von 4 mm bis 4.500 mm<\\\/p>\",\"text_color\":\"emphasis\",\"class\":\"\",\"block_align\":\"center\"}}]}]}],\"modified\":\"2021-10-12T14:05:03.680Z\"},{\"name\":\"Arguments\",\"type\":\"section\",\"props\":{\"width\":\"default\",\"style\":\"default\",\"image_size\":\"cover\",\"image_position\":\"center-center\",\"vertical_align\":\"middle\",\"title_position\":\"top-left\",\"title_rotation\":\"left\",\"title_breakpoint\":\"xl\",\"id\":\"arguments\",\"padding_remove_top\":false},\"children\":[{\"name\":\"\",\"type\":\"row\",\"children\":[{\"name\":\"\",\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"media_overlay_gradient\":\"\",\"width_medium\":\"\",\"position_sticky_breakpoint\":\"m\"},\"children\":[{\"name\":\"\",\"type\":\"headline\",\"props\":{\"title_element\":\"h2\",\"content\":\"Hohe Ma\\u00dfhaltigkeit\",\"title_color\":\"primary\",\"title_style\":\"h1\",\"text_align\":\"center\",\"margin\":\"small\"}},{\"name\":\"\",\"type\":\"headline\",\"props\":{\"title_element\":\"h2\",\"content\":\"Gro\\u00dfe Bandbreite an Abmessungen\",\"title_color\":\"primary\",\"title_style\":\"h1\",\"text_align\":\"center\",\"margin\":\"small\"}},{\"name\":\"\",\"type\":\"headline\",\"props\":{\"title_element\":\"h2\",\"content\":\"Anpassungsf\\u00e4higkeit des Prozesses an spezielle Produkte\",\"title_color\":\"primary\",\"title_style\":\"h1\",\"text_align\":\"center\",\"margin\":\"small\"}},{\"name\":\"\",\"type\":\"headline\",\"props\":{\"title_element\":\"h2\",\"content\":\"Langj\\u00e4hrige Erfahrung und anerkanntes Know-how\",\"title_color\":\"primary\",\"title_style\":\"h1\",\"text_align\":\"center\",\"margin\":\"small\"}},{\"name\":\"\",\"type\":\"headline\",\"props\":{\"title_element\":\"h2\",\"content\":\"Kosteng\\u00fcnstige L\\u00f6sung in Bezug auf Material und Bearbeitung\",\"title_color\":\"primary\",\"title_style\":\"h1\",\"text_align\":\"center\",\"margin\":\"small\"}}]}]}]},{\"name\":\"Exemples d'application\",\"type\":\"section\",\"props\":{\"width\":\"default\",\"style\":\"default\",\"image_size\":\"contain\",\"image_position\":\"center-center\",\"vertical_align\":\"middle\",\"title_position\":\"top-left\",\"title_rotation\":\"left\",\"title_breakpoint\":\"xl\",\"id\":\"exemples\",\"image\":\"\",\"padding_remove_bottom\":false},\"children\":[{\"name\":\"\",\"type\":\"row\",\"children\":[{\"name\":\"\",\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"media_overlay_gradient\":\"\",\"width_medium\":\"\",\"position_sticky_breakpoint\":\"m\"},\"children\":[{\"name\":\"\",\"type\":\"headline\",\"props\":{\"title_element\":\"h2\",\"content\":\"Beispiele f\\u00fcr die Anwendung\"}},{\"type\":\"divider\",\"props\":{\"divider_element\":\"hr\",\"divider_style\":\"small\",\"margin_remove_top\":false}}]}]},{\"name\":\"\",\"type\":\"row\",\"props\":{\"layout\":\"1-2,1-2\"},\"children\":[{\"name\":\"\",\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"media_overlay_gradient\":\"\",\"width_medium\":\"1-2\",\"vertical_align\":\"middle\",\"position_sticky_breakpoint\":\"m\"},\"children\":[{\"type\":\"slideshow\",\"props\":{\"show_title\":true,\"show_meta\":true,\"show_content\":true,\"show_link\":true,\"show_thumbnail\":true,\"slideshow_min_height\":300,\"slideshow_autoplay_pause\":true,\"nav\":\"\",\"nav_position\":\"bottom-center\",\"nav_position_margin\":\"medium\",\"nav_align\":\"center\",\"nav_breakpoint\":\"s\",\"thumbnav_width\":\"100\",\"thumbnav_height\":\"75\",\"thumbnav_svg_color\":\"emphasis\",\"slidenav\":\"default\",\"slidenav_margin\":\"medium\",\"slidenav_breakpoint\":\"s\",\"slidenav_outside_breakpoint\":\"xl\",\"overlay_position\":\"center-left\",\"overlay_animation\":\"parallax\",\"title_element\":\"h3\",\"meta_style\":\"text-meta\",\"meta_align\":\"below-title\",\"meta_element\":\"div\",\"link_text\":\"Read more\",\"link_style\":\"default\",\"margin\":\"default\",\"image_width\":\"960\",\"image_height\":\"590\",\"slideshow_autoplay\":true,\"slideshow_autoplay_interval\":\"4\",\"slidenav_large\":true,\"slidenav_outside_color\":\"\",\"text_color\":\"light\"},\"children\":[{\"type\":\"slideshow_item\",\"props\":{\"image\":\"wp-content\\\/uploads\\\/LBI-Domaines-dapplication-Composants-e\\u0301lectriques-bagues-collectrices.jpg\",\"image_alt\":\"Les Bronzes d'Industrie - Anwendungsbereiche - Elektrische Komponenten - Schleifringe\"}},{\"type\":\"slideshow_item\",\"props\":{\"image\":\"wp-content\\\/uploads\\\/LBI-Domaines-dapplication-Composants-e\\u0301lectriques-bagues-collectrices-03.jpg\",\"image_alt\":\"Les Bronzes d'Industrie - Anwendungsbereiche - Elektrische Komponenten - Schleifringe\"}},{\"type\":\"slideshow_item\",\"props\":{\"image\":\"wp-content\\\/uploads\\\/LBI-Domaines-dapplication-Composants-e\\u0301lectriques-bagues-collectrices-02.jpg\",\"image_alt\":\"Les Bronzes d'Industrie - Anwendungsbereiche - Elektrische Komponenten - Schleifringe\"}}]}]},{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"media_overlay_gradient\":\"\",\"width_medium\":\"1-2\",\"order_first\":\"m\",\"vertical_align\":\"middle\",\"position_sticky_breakpoint\":\"m\"},\"children\":[{\"name\":\"\",\"type\":\"headline\",\"props\":{\"title_element\":\"h3\",\"content\":\"Schleifringe - Radial und axial\",\"title_color\":\"primary\"}},{\"type\":\"list\",\"props\":{\"show_image\":true,\"show_link\":true,\"list_element\":\"ul\",\"column_breakpoint\":\"m\",\"image_svg_color\":\"emphasis\",\"image_align\":\"left\",\"image_vertical_align\":true,\"list_marker\":\"disc\",\"list_type\":\"vertical\",\"list_horizontal_separator\":\", \"},\"children\":[{\"type\":\"list_item\",\"props\":{\"content\":\"\n\n<p>Bearbeitete Ringe mit Endbearbeitung oder roh bearbeitete Ringe<br \\\/>Materialien: Bronze, Messing, Kupferlegierungen, Sonderlegierungen<\\\/p>\"}}]}]}]},{\"name\":\"\",\"type\":\"row\",\"props\":{\"layout\":\"1-2,1-2\"},\"children\":[{\"name\":\"\",\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"media_overlay_gradient\":\"\",\"width_medium\":\"1-2\",\"vertical_align\":\"middle\",\"position_sticky_breakpoint\":\"m\"},\"children\":[{\"type\":\"slideshow\",\"props\":{\"show_title\":true,\"show_meta\":true,\"show_content\":true,\"show_link\":true,\"show_thumbnail\":true,\"slideshow_min_height\":300,\"slideshow_autoplay_pause\":true,\"nav\":\"\",\"nav_position\":\"bottom-center\",\"nav_position_margin\":\"medium\",\"nav_align\":\"center\",\"nav_breakpoint\":\"s\",\"thumbnav_width\":\"100\",\"thumbnav_height\":\"75\",\"thumbnav_svg_color\":\"emphasis\",\"slidenav\":\"default\",\"slidenav_margin\":\"medium\",\"slidenav_breakpoint\":\"s\",\"slidenav_outside_breakpoint\":\"xl\",\"overlay_position\":\"center-left\",\"overlay_animation\":\"parallax\",\"title_element\":\"h3\",\"meta_style\":\"text-meta\",\"meta_align\":\"below-title\",\"meta_element\":\"div\",\"link_text\":\"Read more\",\"link_style\":\"default\",\"margin\":\"default\",\"image_width\":\"960\",\"image_height\":\"590\",\"slideshow_autoplay\":true,\"slideshow_autoplay_interval\":\"4\",\"slidenav_large\":true,\"slidenav_outside_color\":\"\",\"text_color\":\"light\"},\"children\":[{\"type\":\"slideshow_item\",\"props\":{\"image\":\"wp-content\\\/uploads\\\/LBI-Domaines-dapplication-Composants-e\\u0301lectriques-Tube-pour-ligne-de\\u0301lectrozingage.jpg\",\"image_alt\":\"Les Bronzes d'Industrie - Anwendungsbereiche - Elektrische Komponenten - Rohr f\\u00fcr Elektroverzinkungsanlagen\"}},{\"type\":\"slideshow_item\",\"props\":{\"image\":\"wp-content\\\/uploads\\\/LBI-Domaines-dapplication-Composants-e\\u0301lectriques-Collecteur-lignes-de\\u0301lectrozingage.jpg\",\"image_alt\":\"Les Bronzes d'Industrie - Anwendungsbereiche - Elektrische Komponenten - Kollektor f\\u00fcr Elektroverzinkungsleitungen\"}}]}]},{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"media_overlay_gradient\":\"\",\"width_medium\":\"1-2\",\"vertical_align\":\"middle\",\"position_sticky_breakpoint\":\"m\"},\"children\":[{\"name\":\"\",\"type\":\"headline\",\"props\":{\"title_element\":\"h3\",\"content\":\"Kollektoren und Rohre f\\u00fcr Elektroverzinkungsanlagen\",\"title_color\":\"primary\"}},{\"type\":\"list\",\"props\":{\"show_image\":true,\"show_link\":true,\"list_element\":\"ul\",\"column_breakpoint\":\"m\",\"image_svg_color\":\"emphasis\",\"image_align\":\"left\",\"image_vertical_align\":true,\"list_marker\":\"disc\",\"list_type\":\"vertical\",\"list_horizontal_separator\":\", \"},\"children\":[{\"type\":\"list_item\",\"props\":{\"content\":\"\n\n<p>Material: Reines Kupfer<\\\/p>\"}}]}]}]},{\"name\":\"\",\"type\":\"row\",\"props\":{\"layout\":\"1-2,1-2\"},\"children\":[{\"name\":\"\",\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"media_overlay_gradient\":\"\",\"width_medium\":\"1-2\",\"vertical_align\":\"middle\",\"position_sticky_breakpoint\":\"m\"},\"children\":[{\"type\":\"image\",\"props\":{\"margin\":\"default\",\"image_svg_color\":\"emphasis\",\"image\":\"wp-content\\\/uploads\\\/LBI-Domaines-dapplication-Composants-e\\u0301lectriques-Douilles-de-disjoncteur.jpg\",\"image_alt\":\"Les Bronzes d'Industrie - Anwendungsbereiche - Elektrische Komponenten - Unterbrecherbuchsen f\\u00fcr Kraftwerke\",\"link\":\"wp-content\\\/uploads\\\/LBI-Domaines-dapplication-Composants-e\\u0301lectriques-Douilles-de-disjoncteur.jpg\",\"link_target\":\"modal\",\"image_width\":\"960\",\"image_height\":\"590\"}}]},{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"media_overlay_gradient\":\"\",\"width_medium\":\"1-2\",\"order_first\":\"m\",\"vertical_align\":\"middle\",\"position_sticky_breakpoint\":\"m\"},\"children\":[{\"name\":\"\",\"type\":\"headline\",\"props\":{\"title_element\":\"h3\",\"content\":\"Kurzschlussringe f\\u00fcr Kraftwerke\",\"title_color\":\"primary\"}},{\"type\":\"list\",\"props\":{\"show_image\":true,\"show_link\":true,\"list_element\":\"ul\",\"column_breakpoint\":\"m\",\"image_svg_color\":\"emphasis\",\"image_align\":\"left\",\"image_vertical_align\":true,\"list_marker\":\"disc\",\"list_type\":\"vertical\",\"list_horizontal_separator\":\", \"},\"children\":[{\"type\":\"list_item\",\"props\":{\"content\":\"\n\n<p>Material: Kupferlegierungen oder reines Kupfer<\\\/p>\"}}]}]}]},{\"name\":\"\",\"type\":\"row\",\"props\":{\"layout\":\"1-2,1-2\"},\"children\":[{\"name\":\"\",\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"media_overlay_gradient\":\"\",\"width_medium\":\"1-2\",\"vertical_align\":\"middle\",\"position_sticky_breakpoint\":\"m\"},\"children\":[{\"type\":\"image\",\"props\":{\"margin\":\"default\",\"image_svg_color\":\"emphasis\",\"image\":\"wp-content\\\/uploads\\\/LBI-Domaines-dapplication-Composants-e\\u0301lectriques-Anneau-de-disjoncteur.jpg\",\"image_alt\":\"Les Bronzes d'Industrie - Anwendungsbereiche - Elektrische Komponenten - Leistungsschalter f\\u00fcr Kraftwerke\",\"link\":\"wp-content\\\/uploads\\\/LBI-Domaines-dapplication-Composants-e\\u0301lectriques-Anneau-de-disjoncteur.jpg\",\"link_target\":\"modal\",\"image_width\":\"960\",\"image_height\":\"590\",\"status\":\"\"}}]},{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"media_overlay_gradient\":\"\",\"width_medium\":\"1-2\",\"vertical_align\":\"middle\",\"position_sticky_breakpoint\":\"m\"},\"children\":[{\"name\":\"\",\"type\":\"headline\",\"props\":{\"title_element\":\"h3\",\"content\":\"Ringe f\\u00fcr Leistungsschalter f\\u00fcr Kraftwerke\",\"title_color\":\"primary\"}},{\"type\":\"list\",\"props\":{\"show_image\":true,\"show_link\":true,\"list_element\":\"ul\",\"column_breakpoint\":\"m\",\"image_svg_color\":\"emphasis\",\"image_align\":\"left\",\"image_vertical_align\":true,\"list_marker\":\"disc\",\"list_type\":\"vertical\",\"list_horizontal_separator\":\", \"},\"children\":[{\"type\":\"list_item\",\"props\":{\"content\":\"\n\n<p>Material: Kupferlegierungen oder reines Kupfer<\\\/p>\"}}]}]}]},{\"name\":\"\",\"type\":\"row\",\"props\":{\"layout\":\"1-2,1-2\"},\"children\":[{\"name\":\"\",\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"media_overlay_gradient\":\"\",\"width_medium\":\"1-2\",\"vertical_align\":\"middle\",\"position_sticky_breakpoint\":\"m\"},\"children\":[{\"name\":\"\",\"type\":\"headline\",\"props\":{\"title_element\":\"h2\",\"content\":\"Materialien und Ausf\\u00fchrung\"}},{\"type\":\"divider\",\"props\":{\"divider_element\":\"hr\",\"divider_style\":\"small\",\"margin_remove_top\":false}},{\"name\":\"\",\"type\":\"headline\",\"props\":{\"title_element\":\"h3\",\"content\":\"Vorgeschlagene Legierungen\",\"title_color\":\"primary\"}},{\"type\":\"list\",\"props\":{\"show_image\":true,\"show_link\":true,\"list_element\":\"ul\",\"column_breakpoint\":\"m\",\"image_svg_color\":\"emphasis\",\"image_align\":\"left\",\"image_vertical_align\":true,\"list_marker\":\"disc\",\"list_type\":\"vertical\",\"list_horizontal_separator\":\", \"},\"children\":[{\"type\":\"list_item\",\"props\":{\"content\":\"\n\n<p>Messing<\\\/p>\"}},{\"type\":\"list_item\",\"props\":{\"content\":\"\n\n<p>Zinnbronze<\\\/p>\"}},{\"type\":\"list_item\",\"props\":{\"content\":\"\n\n<p>Reines Kupfer<\\\/p>\"}},{\"type\":\"list_item\",\"props\":{\"content\":\"\n\n<p>Kupferlegierungen<\\\/p>\"}},{\"type\":\"list_item\",\"props\":{\"content\":\"\n\n<p>Nach Ihren W\\u00fcnschen<\\\/p>\"}}]},{\"name\":\"\",\"type\":\"headline\",\"props\":{\"title_element\":\"h3\",\"content\":\"Fertigung\",\"title_color\":\"primary\"}},{\"type\":\"list\",\"props\":{\"show_image\":true,\"show_link\":true,\"list_element\":\"ul\",\"column_breakpoint\":\"m\",\"image_svg_color\":\"emphasis\",\"image_align\":\"left\",\"image_vertical_align\":true,\"list_marker\":\"disc\",\"list_type\":\"vertical\",\"list_horizontal_separator\":\", \"},\"children\":[{\"type\":\"list_item\",\"props\":{\"content\":\"\n\n<p>Vorbearbeiten<\\\/p>\"}},{\"type\":\"list_item\",\"props\":{\"content\":\"\n\n<p>Teilweise oder vollst\\u00e4ndige Bearbeitung<\\\/p>\"}}]}]},{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"media_overlay_gradient\":\"\",\"width_medium\":\"1-2\",\"vertical_align\":\"middle\",\"position_sticky_breakpoint\":\"m\"},\"children\":[{\"type\":\"image\",\"props\":{\"margin\":\"default\",\"image_svg_color\":\"emphasis\",\"image\":\"wp-content\\\/uploads\\\/LBI-Produits-Alliages-cuivreux-Galeries-photos-04.jpg\",\"image_alt\":\"Les Bronzes d'Industrie - Anwendungsbereiche - Elektrische Komponenten\",\"link\":\"wp-content\\\/uploads\\\/LBI-Produits-Alliages-cuivreux-Galeries-photos-04.jpg\",\"link_target\":\"modal\",\"image_width\":\"960\",\"image_height\":\"590\"}}]}]}]},{\"name\":\"Autres domaines d'application\",\"type\":\"section\",\"props\":{\"width\":\"default\",\"style\":\"default\",\"image_size\":\"cover\",\"image_position\":\"center-center\",\"vertical_align\":\"middle\",\"title_position\":\"top-left\",\"title_rotation\":\"left\",\"title_breakpoint\":\"xl\",\"id\":\"domaines-application\",\"padding_remove_bottom\":true},\"children\":[{\"name\":\"\",\"type\":\"row\",\"props\":{\"margin_remove_bottom\":false},\"children\":[{\"name\":\"\",\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"media_overlay_gradient\":\"\",\"width_medium\":\"\",\"position_sticky_breakpoint\":\"m\"},\"children\":[{\"name\":\"\",\"type\":\"headline\",\"props\":{\"title_element\":\"h2\",\"content\":\"Andere Anwendungsbereiche\",\"title_color\":\"primary\"}},{\"type\":\"divider\",\"props\":{\"divider_element\":\"hr\",\"divider_style\":\"small\",\"margin_remove_top\":false}}]}]}]},{\"name\":\"Galerie de domaines d'application\",\"type\":\"section\",\"props\":{\"width\":\"default\",\"style\":\"default\",\"image_size\":\"contain\",\"image_position\":\"center-center\",\"vertical_align\":\"middle\",\"title_position\":\"top-left\",\"title_rotation\":\"left\",\"title_breakpoint\":\"xl\",\"image\":\"wp-content\\\/uploads\\\/Fond-jaune.svg\",\"padding_remove_top\":false,\"padding_remove_bottom\":false},\"children\":[{\"name\":\"\",\"type\":\"row\",\"children\":[{\"name\":\"\",\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"media_overlay_gradient\":\"\",\"width_medium\":\"\",\"position_sticky_breakpoint\":\"m\"},\"children\":[{\"type\":\"gallery\",\"props\":{\"show_title\":true,\"show_meta\":false,\"show_content\":false,\"show_link\":true,\"show_hover_image\":false,\"grid_default\":\"2\",\"grid_medium\":\"6\",\"filter_style\":\"tab\",\"filter_all\":true,\"filter_position\":\"top\",\"filter_align\":\"left\",\"filter_grid_width\":\"auto\",\"filter_grid_breakpoint\":\"m\",\"overlay_mode\":\"cover\",\"overlay_hover\":false,\"overlay_style\":\"overlay-primary\",\"text_color\":\"light\",\"overlay_position\":\"center\",\"overlay_transition\":\"scale-up\",\"title_hover_style\":\"reset\",\"title_element\":\"h3\",\"meta_style\":\"text-meta\",\"meta_align\":\"below-title\",\"meta_element\":\"div\",\"link_text\":\"\",\"link_style\":\"\",\"text_align\":\"center\",\"margin\":\"default\",\"item_animation\":true,\"grid_small\":\"3\",\"overlay_transition_background\":false,\"grid_column_gap\":\"medium\",\"grid_row_gap\":\"medium\",\"lightbox\":false,\"title_display\":\"lightbox\",\"content_display\":\"lightbox\",\"image_width\":\"220\",\"image_height\":\"160\",\"image_transition\":\"scale-up\",\"overlay_link\":true,\"text_color_hover\":false,\"overlay_padding\":\"none\",\"title_style\":\"h4\",\"parallax_easing\":\"1\",\"image_loading\":true},\"children\":[{\"type\":\"gallery_item\",\"props\":{\"title\":\"Schiffbau\",\"link\":\"de\\\/anwendungsbereiche\\\/schiffbau\\\/\",\"image\":\"wp-content\\\/uploads\\\/LBI-Domaines-dapplication-Construction-navale-Galeries-photos-01.jpg\",\"image_alt\":\"Les Bronzes d'Industrie - Anwendungsbereiche - Schiffbau\"}},{\"type\":\"gallery_item\",\"props\":{\"title\":\"Turbinen\",\"link\":\"de\\\/anwendungsbereiche\\\/turbinen\\\/\",\"image\":\"wp-content\\\/uploads\\\/LBI-Domaines-dapplication-Turbines-Galeries-photos-01.jpg\",\"image_alt\":\"Les Bronzes d'Industrie - Anwendungsbereiche - Turbinen\"}},{\"type\":\"gallery_item\",\"props\":{\"image\":\"wp-content\\\/uploads\\\/LBI-Domaines-dapplication-Aeronautique-Galeries-photos-01.jpg\",\"image_alt\":\"Les Bronzes d'Industrie - Anwendungsbereiche - Luft- und Raumfahrt\",\"title\":\"Luft- und Raumfahrt\",\"hover_image\":\"\",\"link\":\"de\\\/anwendungsbereiche\\\/luft-und-raumfahrt\\\/\",\"link_text\":\"\"}},{\"type\":\"gallery_item\",\"props\":{\"title\":\"Chemie\",\"link\":\"de\\\/anwendungsbereiche\\\/chemie\\\/\",\"image\":\"wp-content\\\/uploads\\\/LBI-Domaines-dapplication-Chimie-Galeries-photos-01.jpg\",\"image_alt\":\"Les Bronzes d'Industrie - Anwendungsbereiche - Chemie\"}},{\"type\":\"gallery_item\",\"props\":{\"title\":\"Eisen- und Stahlindustrie \\\/ Galvanisierung\",\"link\":\"de\\\/anwendungsbereiche\\\/eisen-und-stahlindustrie-galvanisierung\\\/\",\"image\":\"wp-content\\\/uploads\\\/LBI-Domaines-dapplication-Siderurgie-Galvanisation-Galeries-photos-01.jpg\",\"image_alt\":\"Les Bronzes d'Industrie - Anwendungsbereiche - Eisen- und Stahlindustrie \\\/ Galvanisierung\"}},{\"type\":\"gallery_item\",\"props\":{\"title\":\"Eisen- und Stahlindustrie \\\/ Walzen\",\"link\":\"de\\\/anwendungsbereiche\\\/eisen-und-stahlindustrie-walzen\\\/\",\"image\":\"wp-content\\\/uploads\\\/LBI-Domaines-dapplication-Siderurgie-Laminage-Galeries-photos-01-1.jpg\",\"image_alt\":\"Les Bronzes d'Industrie - Anwendungsbereiche - Eisen- und Stahlindustrie \\\/ Walzen\"}},{\"type\":\"gallery_item\",\"props\":{\"title\":\"Zerkleinern \\\/ Bergbau\",\"link\":\"de\\\/anwendungsbereiche\\\/zerkleinerung-bergbau\\\/\",\"image\":\"wp-content\\\/uploads\\\/LBI-Domaines-dapplication-Broyage-Galeries-photos-01.jpg\",\"image_alt\":\"Les Bronzes d'Industrie - Anwendungsbereiche - Zerkleinern \\\/ Bergbau\"}},{\"type\":\"gallery_item\",\"props\":{\"title\":\"Elektrische Bauteile\",\"link\":\"de\\\/anwendungsbereiche\\\/elektrische-komponenten\\\/\",\"image\":\"wp-content\\\/uploads\\\/LBI-Domaines-dapplication-Composants-electriques-Galeries-photos-01-1.jpg\",\"image_alt\":\"Les Bronzes d'Industrie - Anwendungsbereiche - Elektrische Bauteile\",\"status\":\"disabled\"}},{\"type\":\"gallery_item\",\"props\":{\"title\":\"Werkzeugmaschinen und Pressen\",\"link\":\"de\\\/anwendungsbereiche\\\/werkzeugmaschinen-und-pressen\\\/\",\"image\":\"wp-content\\\/uploads\\\/LBI-Domaines-dapplication-machine-outil-Galeries-photos-01.jpg\",\"image_alt\":\"Les Bronzes d'Industrie - Anwendungsbereiche - Werkzeugmaschinen und Pressen Presses\"}},{\"type\":\"gallery_item\",\"props\":{\"title\":\"Pumpen\",\"link\":\"de\\\/anwendungsbereiche\\\/pumpen\\\/\",\"image\":\"wp-content\\\/uploads\\\/LBI-Domaine-dapplications-Pompes-Galeries-photos-01.jpg\",\"image_alt\":\"Les Bronzes d'Industrie - Anwendungsbereiche - Pumpen\"}},{\"type\":\"gallery_item\",\"props\":{\"title\":\"Armaturen & Ventile\",\"link\":\"de\\\/anwendungsbereiche\\\/armaturen-und-ventile\\\/\",\"image\":\"wp-content\\\/uploads\\\/LBI-Domaines-dapplication-Vannes-Galeries-photos-01.jpg\",\"image_alt\":\"Les Bronzes d'Industrie - Anwendungsbereiche - Armaturen & Ventile\"}}]}]}]}]},{\"name\":\"Principaux agr\\u00e9ments\",\"type\":\"section\",\"props\":{\"width\":\"default\",\"style\":\"default\",\"image_size\":\"cover\",\"image_position\":\"center-center\",\"vertical_align\":\"middle\",\"title_position\":\"top-left\",\"title_rotation\":\"left\",\"title_breakpoint\":\"xl\",\"id\":\"agrements\",\"padding_remove_top\":true,\"padding_remove_bottom\":false},\"children\":[{\"name\":\"\",\"type\":\"row\",\"children\":[{\"name\":\"\",\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"media_overlay_gradient\":\"\",\"width_medium\":\"\",\"position_sticky_breakpoint\":\"m\"},\"children\":[{\"name\":\"\",\"type\":\"headline\",\"props\":{\"title_element\":\"h2\",\"content\":\"Wichtigste Zulassungen\"}},{\"type\":\"divider\",\"props\":{\"divider_element\":\"hr\",\"divider_style\":\"small\",\"margin_remove_top\":false}},{\"type\":\"button\",\"props\":{\"grid_column_gap\":\"small\",\"grid_row_gap\":\"small\",\"margin\":\"default\"},\"children\":[{\"type\":\"button_item\",\"props\":{\"button_style\":\"text\",\"icon_align\":\"right\",\"content\":\"Weitere Informationen\",\"link\":\"de\\\/les-bronzes-dindustrie\\\/zertifizierungen-und-zulassungen\\\/\",\"link_title\":\"Weitere Informationen\",\"icon\":\"arrow-right\"}}]}]}]},{\"name\":\"\",\"type\":\"row\",\"props\":{\"layout\":\"1-2,1-2\",\"class\":\"\",\"column_gap\":\"collapse\",\"margin_remove_bottom\":false},\"children\":[{\"name\":\"\",\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"media_overlay_gradient\":\"\",\"width_medium\":\"1-2\",\"vertical_align\":\"middle\",\"position_sticky_breakpoint\":\"m\"},\"children\":[{\"type\":\"grid\",\"props\":{\"show_title\":true,\"show_meta\":true,\"show_content\":true,\"show_image\":true,\"show_link\":true,\"grid_default\":\"3\",\"grid_medium\":\"\",\"filter_style\":\"tab\",\"filter_all\":true,\"filter_position\":\"top\",\"filter_align\":\"left\",\"filter_grid_width\":\"auto\",\"filter_grid_breakpoint\":\"m\",\"title_hover_style\":\"reset\",\"title_element\":\"h3\",\"title_align\":\"top\",\"title_grid_width\":\"1-2\",\"title_grid_breakpoint\":\"m\",\"meta_style\":\"text-meta\",\"meta_align\":\"below-title\",\"meta_element\":\"div\",\"content_column_breakpoint\":\"m\",\"icon_width\":80,\"image_align\":\"top\",\"image_grid_width\":\"1-2\",\"image_grid_breakpoint\":\"m\",\"image_svg_color\":\"emphasis\",\"link_text\":\"\",\"link_style\":\"default\",\"margin\":\"default\",\"item_animation\":true,\"grid_column_align\":false,\"grid_row_align\":true,\"grid_column_gap\":\"collapse\",\"grid_row_gap\":\"medium\",\"image_width\":\"300\",\"grid_small\":\"6\",\"text_align\":\"left\",\"text_align_breakpoint\":\"m\",\"text_align_fallback\":\"center\",\"image_height\":\"240\",\"title_style\":\"h6\",\"parallax_easing\":\"1\"},\"children\":[{\"type\":\"grid_item\",\"props\":{\"image\":\"wp-content\\\/uploads\\\/ISO-9001-Certification.png\",\"image_alt\":\"Les Bronzes d'Industrie - Zertifizierung ISO 9001\"}},{\"type\":\"grid_item\",\"props\":{\"image\":\"wp-content\\\/uploads\\\/ISO-14001-Certification.png\",\"image_alt\":\"Les Bronzes d'Industrie - Zertifizierung ISO 14001\"}}]}]},{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"media_overlay_gradient\":\"\",\"width_medium\":\"1-2\",\"vertical_align\":\"middle\",\"position_sticky_breakpoint\":\"m\"},\"children\":[]}]}]}],\"version\":\"3.0.5\"} --><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Elektrische Bauteile Au\u00dfendurchmesser bis zu 6.000 mm &#8211; L\u00e4nge von 4 mm bis 4.500 mm Hohe Ma\u00dfhaltigkeit Gro\u00dfe Bandbreite an Abmessungen Anpassungsf\u00e4higkeit des Prozesses an spezielle Produkte Langj\u00e4hrige Erfahrung und anerkanntes Know-how Kosteng\u00fcnstige L\u00f6sung in Bezug auf Material und Bearbeitung Beispiele f\u00fcr die Anwendung Schleifringe &#8211; Radial und axial Bearbeitete Ringe mit Endbearbeitung oder roh [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"parent":1525,"menu_order":7,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-1533","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Teile f\u00fcr elektrische Bauteile - Les Bronzes d&#039;Industrie<\/title>\n<meta name=\"description\" content=\"Gro\u00dfe Auswahl an schleudergegossenen Produkten f\u00fcr elektrische Bauteile: Schleifringe, Kollektoren, Leistungsschalterbuchsen, Ringe f\u00fcr Leistungsschalter, Kurzschlussringe.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lbi.fr\/de\/anwendungsbereiche\/elektrische-komponenten\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Teile f\u00fcr elektrische Bauteile - Les Bronzes d&#039;Industrie\" \/>\n<meta property=\"og:description\" content=\"Gro\u00dfe Auswahl an schleudergegossenen Produkten f\u00fcr elektrische Bauteile: Schleifringe, Kollektoren, Leistungsschalterbuchsen, Ringe f\u00fcr Leistungsschalter, Kurzschlussringe.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lbi.fr\/de\/anwendungsbereiche\/elektrische-komponenten\/\" \/>\n<meta property=\"og:site_name\" content=\"Les Bronzes d&#039;Industrie\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-21T09:15:33+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"7\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lbi.fr\\\/de\\\/anwendungsbereiche\\\/elektrische-komponenten\\\/\",\"url\":\"https:\\\/\\\/www.lbi.fr\\\/de\\\/anwendungsbereiche\\\/elektrische-komponenten\\\/\",\"name\":\"Teile f\u00fcr elektrische Bauteile - Les Bronzes d&#039;Industrie\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lbi.fr\\\/de\\\/#website\"},\"datePublished\":\"2022-10-18T15:16:58+00:00\",\"dateModified\":\"2022-10-21T09:15:33+00:00\",\"description\":\"Gro\u00dfe Auswahl an schleudergegossenen Produkten f\u00fcr elektrische Bauteile: Schleifringe, Kollektoren, Leistungsschalterbuchsen, Ringe f\u00fcr Leistungsschalter, Kurzschlussringe.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lbi.fr\\\/de\\\/anwendungsbereiche\\\/elektrische-komponenten\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lbi.fr\\\/de\\\/anwendungsbereiche\\\/elektrische-komponenten\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lbi.fr\\\/de\\\/anwendungsbereiche\\\/elektrische-komponenten\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.lbi.fr\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Anwendungsbereiche\",\"item\":\"https:\\\/\\\/www.lbi.fr\\\/de\\\/anwendungsbereiche\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Elektrische Komponenten\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lbi.fr\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.lbi.fr\\\/de\\\/\",\"name\":\"Les Bronzes d&#039;Industrie\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.lbi.fr\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lbi.fr\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.lbi.fr\\\/de\\\/#organization\",\"name\":\"Les Bronzes d'Industrie\",\"url\":\"https:\\\/\\\/www.lbi.fr\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.lbi.fr\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.lbi.fr\\\/wp-content\\\/uploads\\\/LBI-Logo-RVB.png\",\"contentUrl\":\"https:\\\/\\\/www.lbi.fr\\\/wp-content\\\/uploads\\\/LBI-Logo-RVB.png\",\"width\":800,\"height\":600,\"caption\":\"Les Bronzes d'Industrie\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lbi.fr\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lbi-lesbronzesd'industrie\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Teile f\u00fcr elektrische Bauteile - Les Bronzes d&#039;Industrie","description":"Gro\u00dfe Auswahl an schleudergegossenen Produkten f\u00fcr elektrische Bauteile: Schleifringe, Kollektoren, Leistungsschalterbuchsen, Ringe f\u00fcr Leistungsschalter, Kurzschlussringe.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lbi.fr\/de\/anwendungsbereiche\/elektrische-komponenten\/","og_locale":"de_DE","og_type":"article","og_title":"Teile f\u00fcr elektrische Bauteile - Les Bronzes d&#039;Industrie","og_description":"Gro\u00dfe Auswahl an schleudergegossenen Produkten f\u00fcr elektrische Bauteile: Schleifringe, Kollektoren, Leistungsschalterbuchsen, Ringe f\u00fcr Leistungsschalter, Kurzschlussringe.","og_url":"https:\/\/www.lbi.fr\/de\/anwendungsbereiche\/elektrische-komponenten\/","og_site_name":"Les Bronzes d&#039;Industrie","article_modified_time":"2022-10-21T09:15:33+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"7\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.lbi.fr\/de\/anwendungsbereiche\/elektrische-komponenten\/","url":"https:\/\/www.lbi.fr\/de\/anwendungsbereiche\/elektrische-komponenten\/","name":"Teile f\u00fcr elektrische Bauteile - Les Bronzes d&#039;Industrie","isPartOf":{"@id":"https:\/\/www.lbi.fr\/de\/#website"},"datePublished":"2022-10-18T15:16:58+00:00","dateModified":"2022-10-21T09:15:33+00:00","description":"Gro\u00dfe Auswahl an schleudergegossenen Produkten f\u00fcr elektrische Bauteile: Schleifringe, Kollektoren, Leistungsschalterbuchsen, Ringe f\u00fcr Leistungsschalter, Kurzschlussringe.","breadcrumb":{"@id":"https:\/\/www.lbi.fr\/de\/anwendungsbereiche\/elektrische-komponenten\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lbi.fr\/de\/anwendungsbereiche\/elektrische-komponenten\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.lbi.fr\/de\/anwendungsbereiche\/elektrische-komponenten\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.lbi.fr\/de\/"},{"@type":"ListItem","position":2,"name":"Anwendungsbereiche","item":"https:\/\/www.lbi.fr\/de\/anwendungsbereiche\/"},{"@type":"ListItem","position":3,"name":"Elektrische Komponenten"}]},{"@type":"WebSite","@id":"https:\/\/www.lbi.fr\/de\/#website","url":"https:\/\/www.lbi.fr\/de\/","name":"Les Bronzes d&#039;Industrie","description":"","publisher":{"@id":"https:\/\/www.lbi.fr\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lbi.fr\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.lbi.fr\/de\/#organization","name":"Les Bronzes d'Industrie","url":"https:\/\/www.lbi.fr\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.lbi.fr\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.lbi.fr\/wp-content\/uploads\/LBI-Logo-RVB.png","contentUrl":"https:\/\/www.lbi.fr\/wp-content\/uploads\/LBI-Logo-RVB.png","width":800,"height":600,"caption":"Les Bronzes d'Industrie"},"image":{"@id":"https:\/\/www.lbi.fr\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/lbi-lesbronzesd'industrie\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.lbi.fr\/de\/wp-json\/wp\/v2\/pages\/1533","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lbi.fr\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.lbi.fr\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.lbi.fr\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lbi.fr\/de\/wp-json\/wp\/v2\/comments?post=1533"}],"version-history":[{"count":0,"href":"https:\/\/www.lbi.fr\/de\/wp-json\/wp\/v2\/pages\/1533\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.lbi.fr\/de\/wp-json\/wp\/v2\/pages\/1525"}],"wp:attachment":[{"href":"https:\/\/www.lbi.fr\/de\/wp-json\/wp\/v2\/media?parent=1533"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}